{"id":1174,"date":"2014-06-26T11:56:44","date_gmt":"2014-06-26T10:56:44","guid":{"rendered":"http:\/\/www.canyon-nice.fr\/blog\/?p=1174"},"modified":"2014-06-26T11:56:44","modified_gmt":"2014-06-26T10:56:44","slug":"via-des-canyons-de-lantosque-ou-les-demoiselles-de-castagnet-a-puget-theniers","status":"publish","type":"post","link":"http:\/\/www.canyon-nice.fr\/blog\/2014\/06\/26\/via-des-canyons-de-lantosque-ou-les-demoiselles-de-castagnet-a-puget-theniers\/","title":{"rendered":"Via des canyons de Lantosque ou les demoiselles de Castagnet \u00e0 Puget-Th\u00e9niers ?"},"content":{"rendered":"<p style=\"text-align: justify;\">Derni\u00e8rement, il m&rsquo;a \u00e9t\u00e9 donn\u00e9 l&rsquo;occasion de parcourir ces deux via ferrata. Je connaissais tr\u00e8s bien <a href=\"http:\/\/www.puget-theniers.fr\/index.php?id=8353\" target=\"_blank\">Puget<\/a> mais cela faisait longtemps que je n&rsquo;avais plus mis les pieds \u00e0 <a href=\"http:\/\/www.via-ferrata-lantosque.fr\/\" target=\"_blank\">Lantosque<\/a> pour autre chose que la Boll\u00e8ne. Petit comparatif !<\/p>\n<p style=\"text-align: justify;\">La via de Puget est sans conteste plus difficile que celle de Lantosque. Sans pour autant \u00eatre physique, elle est longue et d\u00e9marre par une longue ascension sans \u00e9chappatoire. Une fois atteintes les cr\u00eates, la difficult\u00e9 se calme pour faire place aux sensations avec le long pont de singe et la tyrolienne. La marche de retour n&rsquo;est pas non plus \u00e0 n\u00e9gliger. M\u00eame si elle descend, il faut compter 20 bonnes minutes avant de retrouver les voitures.<\/p>\n<p style=\"text-align: justify;\">ngg_shortcode_0_placeholder<\/p>\n<p style=\"text-align: justify;\">A Lantosque, nous ne trouvons aucune section physique, ni rien de bien impressionnant si ce n&rsquo;est quelques ponts de singe au dessus des eaux tumultueuses de la V\u00e9subie. La derni\u00e8re ascension pour atteindre le pont final n&rsquo;est pas difficile et le parcours globalement moins long. La marche d&rsquo;approche comme la marche de retour sont \u00e9galement minimes.<\/p>\n<p style=\"text-align: justify;\">ngg_shortcode_1_placeholder<\/p>\n<p style=\"text-align: justify;\">Question ambiance, difficile de faire plus diff\u00e9rent. Puget est une via a\u00e9rienne qui offre des paysages de montagne sur fond de vall\u00e9e du Var. A moins de partir tr\u00e8s t\u00f4t, la majeure partie de la via est au soleil, ce qui peut la rendre p\u00e9nible par grosses chaleurs. Pr\u00e9voyez de l&rsquo;eau en abondance !<\/p>\n<p style=\"text-align: justify;\">ngg_shortcode_2_placeholder<\/p>\n<p style=\"text-align: justify;\">A Lantosque,\u00a0 La via se situe sous le village, sur les bords du riou de Lantosque d&rsquo;abord, puis au dessus de la V\u00e9subie ensuite. Le point d&rsquo;orgue de la via se situe d&rsquo;ailleurs \u00e0 la confluence des deux rivi\u00e8res, avec un pont de singe enjambant la cascade et le passage sur la boule coinc\u00e9e. Cette via est donc tr\u00e8s ombrag\u00e9e et humide, et donc bien adapt\u00e9e en \u00e9t\u00e9. Beaucoup moins en hiver ! Elle n&rsquo;est d&rsquo;ailleurs ouverte que de juin \u00e0 octobre.<\/p>\n<p style=\"text-align: justify;\">ngg_shortcode_3_placeholder<\/p>\n<p style=\"text-align: justify;\">Ces deux via des Alpes Maritimes sont donc assez radicalement oppos\u00e9es. Lantosque est \u00e0 privil\u00e9gier lors de grosses chaleurs mais pourrait para\u00eetre trop facile \u00e0 certains, voire trop urbaine. Puget offre de meilleures sensation pour un niveau sportif plus soutenu et des paysages plus ouverts. Les tarifs d&rsquo;entr\u00e9e et de location sont similaires : \u00e0 vous de choisir donc !<\/p>\n<p style=\"text-align: justify;\">Via ferrata de Puget :<\/p>\n<p style=\"text-align: justify;\">[Not a valid template]<\/p>\n<p style=\"text-align: justify;\">Via ferrata de Lantosque :<\/p>\n<p style=\"text-align: justify;\">[Not a valid template]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derni\u00e8rement, il m&rsquo;a \u00e9t\u00e9 donn\u00e9 l&rsquo;occasion de parcourir ces deux via ferrata. Je connaissais tr\u00e8s bien Puget mais cela faisait longtemps que je n&rsquo;avais plus mis les pieds \u00e0 Lantosque pour autre chose que la Boll\u00e8ne. Petit comparatif ! La &hellip; <a href=\"http:\/\/www.canyon-nice.fr\/blog\/2014\/06\/26\/via-des-canyons-de-lantosque-ou-les-demoiselles-de-castagnet-a-puget-theniers\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[120,119,176,177],"_links":{"self":[{"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/posts\/1174"}],"collection":[{"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":6,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/posts\/1174\/revisions"}],"predecessor-version":[{"id":1218,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/posts\/1174\/revisions\/1218"}],"wp:attachment":[{"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/categories?post=1174"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.canyon-nice.fr\/blog\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}